{"id":194297,"date":"2025-05-22T10:05:18","date_gmt":"2025-05-22T10:05:18","guid":{"rendered":"https:\/\/aigroupfood.net\/us\/product\/100-shield-nitrile-5mil-powder-free-gloves-black-latex-vinyl-free-medium\/"},"modified":"2025-05-22T10:05:19","modified_gmt":"2025-05-22T10:05:19","slug":"100-shield-nitrile-5mil-powder-free-gloves-black-latex-vinyl-free-medium","status":"publish","type":"product","link":"https:\/\/aigroupfood.net\/us\/product\/100-shield-nitrile-5mil-powder-free-gloves-black-latex-vinyl-free-medium\/","title":{"rendered":"100 Shield\u2122 Nitrile 5mil Powder Free Gloves Black (Latex Vinyl Free) Medium"},"content":{"rendered":"<p>At supplyhut LLC we strive for 100% customer satisfaction. If you are not satisfied do not leave negative feedback in retaliation for a defective product or something you were not expecting. Please just contact us through Walmart messages and we will quickly resolve the matter. Also always remember to leave 5 stars for each of the 4 categories when leaving feedback.100 Shield\u2122 Nitrile 5mil Powder Free Gloves Black (Latex Vinyl Free) Medium<\/p>\n","protected":false},"excerpt":{"rendered":"<p>At supplyhut LLC we strive for 100% customer satisfaction. If you are not satisfied do not leave negative feedback in retaliation for a defective product or something you were not expecting. Please just contact us through Walmart messages and we will quickly resolve the matter. Also always remember to leave 5 stars for each of [&#8230;]\n","protected":false},"featured_media":194296,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[117415],"product_tag":[168881,225293,225292,225294,225296,115954,181010,225295],"class_list":{"0":"post-194297","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-disposable-gloves","7":"product_tag-free-gloves","8":"product_tag-free-gloves-black","9":"product_tag-gloves-black","10":"product_tag-latex-vinyl","11":"product_tag-latex-vinyl-free","12":"product_tag-powder-free","13":"product_tag-powder-free-gloves","14":"product_tag-vinyl-free","16":"first","17":"instock","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/product\/194297","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/comments?post=194297"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/media\/194296"}],"wp:attachment":[{"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/media?parent=194297"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/product_brand?post=194297"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/product_cat?post=194297"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aigroupfood.net\/us\/wp-json\/wp\/v2\/product_tag?post=194297"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}