{"id":32420,"date":"2025-06-21T02:06:14","date_gmt":"2025-06-21T02:06:14","guid":{"rendered":"https:\/\/aigroupfood.net\/wm-dealzone\/product\/mchoice-1-pcs-easter-decorations-easter-gnome-faceless-plush-doll-bunny-gnomes-ornaments-easter-desktop-bunny-easter-gnome-indoor-spring-decor-easter-gifts-for-kids-women-men\/"},"modified":"2025-06-21T02:06:14","modified_gmt":"2025-06-21T02:06:14","slug":"mchoice-1-pcs-easter-decorations-easter-gnome-faceless-plush-doll-bunny-gnomes-ornaments-easter-desktop-bunny-easter-gnome-indoor-spring-decor-easter-gifts-for-kids-women-men","status":"publish","type":"product","link":"https:\/\/aigroupfood.net\/wm-dealzone\/product\/mchoice-1-pcs-easter-decorations-easter-gnome-faceless-plush-doll-bunny-gnomes-ornaments-easter-desktop-bunny-easter-gnome-indoor-spring-decor-easter-gifts-for-kids-women-men\/","title":{"rendered":"Mchoice 1 Pcs Easter Decorations, Easter Gnome Faceless Plush Doll, Bunny Gnomes Ornaments, Easter Desktop Bunny Easter Gnome, Indoor Spring Decor, Easter Gifts for Kids\/Women\/Men"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":32419,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[15],"product_tag":[48611,48628,48630,48622,48624,48626,48629,48613,48625,48627,48615,48617,48618,48621,48616,48619,48623,48631,48633,48612,48614,48620,48632],"class_list":{"0":"post-32420","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorized","7":"product_tag-mchoice","8":"product_tag-bunny-easter","9":"product_tag-bunny-easter-gnome","10":"product_tag-bunny-gnomes","11":"product_tag-bunny-gnomes-ornaments","12":"product_tag-desktop-bunny","13":"product_tag-desktop-bunny-easter","14":"product_tag-easter-decorations","15":"product_tag-easter-desktop","16":"product_tag-easter-desktop-bunny","17":"product_tag-easter-gnome","18":"product_tag-easter-gnome-faceless","19":"product_tag-faceless-plush","20":"product_tag-faceless-plush-doll","21":"product_tag-gnome-faceless","22":"product_tag-gnome-faceless-plush","23":"product_tag-gnomes-ornaments","24":"product_tag-indoor-spring","25":"product_tag-indoor-spring-decor","26":"product_tag-pcs-easter","27":"product_tag-pcs-easter-decorations","28":"product_tag-plush-doll","29":"product_tag-spring-decor","31":"first","32":"instock","33":"taxable","34":"shipping-taxable","35":"purchasable","36":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product\/32420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/comments?post=32420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/media\/32419"}],"wp:attachment":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/media?parent=32420"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product_brand?post=32420"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product_cat?post=32420"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product_tag?post=32420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}