{"id":4407,"date":"2025-06-20T10:30:50","date_gmt":"2025-06-20T10:30:50","guid":{"rendered":"https:\/\/aigroupfood.net\/wm-dealzone\/product\/feverall-acetaminophen-suppositories-jr-strength-6-ea\/"},"modified":"2025-06-20T10:30:50","modified_gmt":"2025-06-20T10:30:50","slug":"feverall-acetaminophen-suppositories-jr-strength-6-ea","status":"publish","type":"product","link":"https:\/\/aigroupfood.net\/wm-dealzone\/product\/feverall-acetaminophen-suppositories-jr-strength-6-ea\/","title":{"rendered":"FeverAll Acetaminophen Suppositories Jr. Strength &#8211; 6 ea"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":4406,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[15],"product_tag":[8214,8217,8213,8215,8218,8216,8219],"class_list":{"0":"post-4407","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-uncategorized","7":"product_tag-acetaminophen-suppositories","8":"product_tag-acetaminophen-suppositories-jr","9":"product_tag-feverall-acetaminophen","10":"product_tag-feverall-acetaminophen-suppositories","11":"product_tag-jr-strength","12":"product_tag-suppositories-jr","13":"product_tag-suppositories-jr-strength","15":"first","16":"instock","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product\/4407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/comments?post=4407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/media\/4406"}],"wp:attachment":[{"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/media?parent=4407"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product_brand?post=4407"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product_cat?post=4407"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/aigroupfood.net\/wm-dealzone\/wp-json\/wp\/v2\/product_tag?post=4407"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}